{"id":9417,"date":"2025-07-28T09:13:09","date_gmt":"2025-07-28T07:13:09","guid":{"rendered":"https:\/\/consejojuventudcalahorra.com\/cjcc\/?p=9417"},"modified":"2025-07-28T09:13:09","modified_gmt":"2025-07-28T07:13:09","slug":"abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra","status":"publish","type":"post","link":"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/","title":{"rendered":"Abierto el plazo de inscripci\u00f3n para el Taller de Estrellas del Consejo de la Juventud Comarcal de Calahorra"},"content":{"rendered":"<p align=\"center\"><b>Se desarrollar\u00e1 el d\u00eda 12 de agosto y las inscripciones son gratuitas y limitadas<u><\/u><u><\/u><\/b><\/p>\n<p>El Consejo de la Juventud Comarcal de Calahorra ha abierto el plazo de inscripci\u00f3n para su pr\u00f3ximo\u00a0<strong>Taller de Estrellas<\/strong>, una actividad gratuita que se celebrar\u00e1 el\u00a0<strong>martes 12 de agosto<\/strong>\u00a0a las 20:00 h.<u><\/u><u><\/u><\/p>\n<p>El taller comenzar\u00e1 con una\u00a0<strong>sesi\u00f3n te\u00f3rica\u00a0<\/strong>en el Centro Joven de Calahorra, en la que la\u00a0<strong>astrof\u00edsica Ana Urs\u00faa<\/strong>\u00a0compartir\u00e1 sus conocimientos sobre astronom\u00eda de forma did\u00e1ctica y cercana. Durante esta primera parte, tambi\u00e9n elaboraremos\u00a0<strong>planisferios personalizados<\/strong>\u00a0y nos prepararemos para la observaci\u00f3n astron\u00f3mica.<u><\/u><u><\/u><\/p>\n<p>A continuaci\u00f3n, realizaremos una\u00a0<strong>salida al aire libre<\/strong>\u00a0para contemplar el cielo nocturno y, si las condiciones lo permiten, disfrutar del fen\u00f3meno de las\u00a0<strong>estrellas fugaces<\/strong>.\u00a0<u><\/u><u><\/u><\/p>\n<p>Este taller supone el\u00a0<strong>primer paso hacia el gran acontecimiento astron\u00f3mico que viviremos el 12 de agosto de 2026<\/strong>, cuando tendr\u00e1 lugar un\u00a0<strong>eclipse total de Sol<\/strong>\u00a0visible desde nuestra zona. Un evento \u00fanico que nos permitir\u00e1 disfrutar de casi\u00a0<strong>dos minutos de oscuridad total en pleno d\u00eda<\/strong>, y sobre el que empezaremos a formarnos desde ahora.<u><\/u><u><\/u><\/p>\n<p>La participaci\u00f3n en esta actividad es\u00a0<strong>gratuita<\/strong>\u00a0y las\u00a0<b>plazas son limitadas<\/b>, por lo que se recomienda a las personas interesadas\u00a0<b>inscribirse<\/b>\u00a0lo antes posible a trav\u00e9s de nuestro\u00a0<b>WhatsApp en 667463791<\/b><u><\/u><u><\/u><\/p>\n<p>Desde el Consejo de la Juventud Comarcal de Calahorra queremos expresar nuestro agradecimiento al\u00a0<strong>Ayuntamiento de Calahorra<\/strong>\u00a0y al\u00a0<strong>Instituto Riojano de la Juventud<\/strong><b>,<\/b>\u00a0cuyo apoyo ha sido fundamental para poder llevar a cabo este taller.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9418\" src=\"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/07\/2025_07_28-taller-de-estrellas-212x300.jpeg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/07\/2025_07_28-taller-de-estrellas-212x300.jpeg 212w, https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/07\/2025_07_28-taller-de-estrellas.jpeg 452w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se desarrollar\u00e1 el d\u00eda 12 de agosto y las inscripciones son gratuitas y limitadas El Consejo de la Juventud Comarcal de Calahorra ha abierto el plazo de inscripci\u00f3n para su [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9418,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[24],"tags":[],"class_list":["post-9417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ocio-y-tiempo-libre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abierto el plazo de inscripci\u00f3n para el Taller de Estrellas del Consejo de la Juventud Comarcal de Calahorra - Consejo de la Juventud Comarcal de Calahorra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abierto el plazo de inscripci\u00f3n para el Taller de Estrellas del Consejo de la Juventud Comarcal de Calahorra - Consejo de la Juventud Comarcal de Calahorra\" \/>\n<meta property=\"og:description\" content=\"Se desarrollar\u00e1 el d\u00eda 12 de agosto y las inscripciones son gratuitas y limitadas El Consejo de la Juventud Comarcal de Calahorra ha abierto el plazo de inscripci\u00f3n para su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo de la Juventud Comarcal de Calahorra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/consejojuventudcalahorra\/?locale=es_ES\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-28T07:13:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/07\/2025_07_28-taller-de-estrellas.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"452\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#\\\/schema\\\/person\\\/d253aff657149d7ba139596a2830074c\"},\"headline\":\"Abierto el plazo de inscripci\u00f3n para el Taller de Estrellas del Consejo de la Juventud Comarcal de Calahorra\",\"datePublished\":\"2025-07-28T07:13:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\\\/\"},\"wordCount\":276,\"publisher\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/2025_07_28-taller-de-estrellas.jpeg\",\"articleSection\":[\"ocio y tiempo libre\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\\\/\",\"url\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\\\/\",\"name\":\"Abierto el plazo de inscripci\u00f3n para el Taller de Estrellas del Consejo de la Juventud Comarcal de Calahorra - Consejo de la Juventud Comarcal de Calahorra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/2025_07_28-taller-de-estrellas.jpeg\",\"datePublished\":\"2025-07-28T07:13:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/2025_07_28-taller-de-estrellas.jpeg\",\"contentUrl\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/2025_07_28-taller-de-estrellas.jpeg\",\"width\":452,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abierto el plazo de inscripci\u00f3n para el Taller de Estrellas del Consejo de la Juventud Comarcal de Calahorra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#website\",\"url\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/\",\"name\":\"Consejo de la Juventud Comarcal de Calahorra\",\"description\":\"Ser joven es ser algo m\u00e1s\",\"publisher\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#organization\",\"name\":\"Consejo de la Juventud Comarcal de Calahorra\",\"url\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-CJCC.png\",\"contentUrl\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-CJCC.png\",\"width\":964,\"height\":660,\"caption\":\"Consejo de la Juventud Comarcal de Calahorra\"},\"image\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/consejojuventudcalahorra\\\/?locale=es_ES\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#\\\/schema\\\/person\\\/d253aff657149d7ba139596a2830074c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f0b7317fa677050c42e96a8889faba4627de455222163352845fae03deb3bb4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f0b7317fa677050c42e96a8889faba4627de455222163352845fae03deb3bb4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f0b7317fa677050c42e96a8889faba4627de455222163352845fae03deb3bb4?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abierto el plazo de inscripci\u00f3n para el Taller de Estrellas del Consejo de la Juventud Comarcal de Calahorra - Consejo de la Juventud Comarcal de Calahorra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/","og_locale":"es_ES","og_type":"article","og_title":"Abierto el plazo de inscripci\u00f3n para el Taller de Estrellas del Consejo de la Juventud Comarcal de Calahorra - Consejo de la Juventud Comarcal de Calahorra","og_description":"Se desarrollar\u00e1 el d\u00eda 12 de agosto y las inscripciones son gratuitas y limitadas El Consejo de la Juventud Comarcal de Calahorra ha abierto el plazo de inscripci\u00f3n para su [&hellip;]","og_url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/","og_site_name":"Consejo de la Juventud Comarcal de Calahorra","article_publisher":"https:\/\/www.facebook.com\/consejojuventudcalahorra\/?locale=es_ES","article_published_time":"2025-07-28T07:13:09+00:00","og_image":[{"width":452,"height":640,"url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/07\/2025_07_28-taller-de-estrellas.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/#article","isPartOf":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/"},"author":{"name":"admin","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#\/schema\/person\/d253aff657149d7ba139596a2830074c"},"headline":"Abierto el plazo de inscripci\u00f3n para el Taller de Estrellas del Consejo de la Juventud Comarcal de Calahorra","datePublished":"2025-07-28T07:13:09+00:00","mainEntityOfPage":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/"},"wordCount":276,"publisher":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#organization"},"image":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/#primaryimage"},"thumbnailUrl":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/07\/2025_07_28-taller-de-estrellas.jpeg","articleSection":["ocio y tiempo libre"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/","url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/","name":"Abierto el plazo de inscripci\u00f3n para el Taller de Estrellas del Consejo de la Juventud Comarcal de Calahorra - Consejo de la Juventud Comarcal de Calahorra","isPartOf":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/#primaryimage"},"image":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/#primaryimage"},"thumbnailUrl":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/07\/2025_07_28-taller-de-estrellas.jpeg","datePublished":"2025-07-28T07:13:09+00:00","breadcrumb":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/#primaryimage","url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/07\/2025_07_28-taller-de-estrellas.jpeg","contentUrl":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/07\/2025_07_28-taller-de-estrellas.jpeg","width":452,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/abierto-el-plazo-de-inscripcion-para-el-taller-de-estrellas-del-consejo-de-la-juventud-comarcal-de-calahorra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/consejojuventudcalahorra.com\/cjcc\/"},{"@type":"ListItem","position":2,"name":"Abierto el plazo de inscripci\u00f3n para el Taller de Estrellas del Consejo de la Juventud Comarcal de Calahorra"}]},{"@type":"WebSite","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#website","url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/","name":"Consejo de la Juventud Comarcal de Calahorra","description":"Ser joven es ser algo m\u00e1s","publisher":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/consejojuventudcalahorra.com\/cjcc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#organization","name":"Consejo de la Juventud Comarcal de Calahorra","url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#\/schema\/logo\/image\/","url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/09\/Logo-CJCC.png","contentUrl":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/09\/Logo-CJCC.png","width":964,"height":660,"caption":"Consejo de la Juventud Comarcal de Calahorra"},"image":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/consejojuventudcalahorra\/?locale=es_ES"]},{"@type":"Person","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#\/schema\/person\/d253aff657149d7ba139596a2830074c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7f0b7317fa677050c42e96a8889faba4627de455222163352845fae03deb3bb4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f0b7317fa677050c42e96a8889faba4627de455222163352845fae03deb3bb4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f0b7317fa677050c42e96a8889faba4627de455222163352845fae03deb3bb4?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/posts\/9417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/comments?post=9417"}],"version-history":[{"count":1,"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/posts\/9417\/revisions"}],"predecessor-version":[{"id":9419,"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/posts\/9417\/revisions\/9419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/media\/9418"}],"wp:attachment":[{"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/media?parent=9417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/categories?post=9417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/tags?post=9417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}