{"id":8258,"date":"2025-03-31T09:31:56","date_gmt":"2025-03-31T07:31:56","guid":{"rendered":"https:\/\/consejojuventudcalahorra.com\/cjcc\/?p=8258"},"modified":"2025-06-25T09:49:59","modified_gmt":"2025-06-25T07:49:59","slug":"deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre","status":"publish","type":"post","link":"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/","title":{"rendered":"\u00abDeja tu huella\u00bb Nueva fase de la campa\u00f1a de sensibilizaci\u00f3n social, ahora centrada en el juego y la educaci\u00f3n en el tiempo libre"},"content":{"rendered":"<p style=\"font-weight: 400;\">El Consejo de la Juventud Comarcal de Calahorra se complace en anunciar una nueva fase dentro de su campa\u00f1a de sensibilizaci\u00f3n social\u00a0<strong>\u201cDeja tu huella\u201d<\/strong>, que en esta ocasi\u00f3n pone el foco en la\u00a0<strong>necesidad de favorecer el juego y la educaci\u00f3n en el tiempo libre<\/strong>\u00a0como herramientas clave para el desarrollo personal y social de la juventud.<\/p>\n<p style=\"font-weight: 400;\">Esta nueva l\u00ednea de trabajo se suma a los objetivos ya impulsados desde la campa\u00f1a inicial, centrada en la promoci\u00f3n del\u00a0<strong>voluntariado y el asociacionismo<\/strong>, y refuerza nuestra convicci\u00f3n de que el tiempo libre, bien orientado, es un espacio fundamental para el crecimiento integral de los j\u00f3venes.<\/p>\n<p style=\"font-weight: 400;\"><strong>El juego, la creatividad y la participaci\u00f3n activa<\/strong>\u00a0son pilares esenciales en la construcci\u00f3n de una ciudadan\u00eda cr\u00edtica, emp\u00e1tica y comprometida. Por ello, a trav\u00e9s de acciones como talleres, jornadas de juegos de mesa, encuentros con asociaciones y charlas en centros educativos, buscamos\u00a0<strong>sensibilizar a la juventud sobre la importancia de aprovechar el tiempo libre de manera constructiva y participativa<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">En d\u00edas pasados iniciamos las charlas en educaci\u00f3n secundaria en el Colegio de Santa Teresa de Jes\u00fas e iremos continuando por todos los centros educativos de secundaria de la comarca.<\/p>\n<p style=\"font-weight: 400;\">Esta fase de la campa\u00f1a tiene como objetivo\u00a0<strong>reivindicar el derecho al juego, el ocio saludable y la educaci\u00f3n no formal<\/strong>, poniendo en valor su capacidad para fomentar habilidades sociales, valores democr\u00e1ticos, autonom\u00eda personal y bienestar emocional.<\/p>\n<p style=\"font-weight: 400;\">Continuamos con nuestra labor de informar, motivar y acompa\u00f1ar a los j\u00f3venes en el descubrimiento de las m\u00faltiples formas en que pueden implicarse activamente en su comarca ya sea\u00a0<strong>a trav\u00e9s del voluntariado, el asociacionismo, o mediante experiencias educativas en el tiempo libre<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">Desde el Consejo de la Juventud Comarcal de Calahorra animamos a todos los j\u00f3venes a\u00a0<strong>dejar su huella<\/strong>tambi\u00e9n a trav\u00e9s del juego, la cooperaci\u00f3n y la participaci\u00f3n activa en actividades que transforman su entorno y enriquecen su desarrollo personal.<\/p>\n<p style=\"font-weight: 400;\">Esta iniciativa cuenta con el apoyo del\u00a0<strong>Ayuntamiento de Calahorra<\/strong>\u00a0y del\u00a0<strong>Instituto Riojano de la Juventud\u00a0<\/strong>quienes, junto a nuestro Consejo, creemos firmemente en el poder transformador de la juventud.<\/p>\n<p style=\"font-weight: 400;\">Para m\u00e1s informaci\u00f3n:<\/p>\n<p style=\"font-weight: 400;\"><strong>Consejo de la Juventud Comarcal de Calahorra<\/strong><br \/>\n<a href=\"http:\/\/www.consejojuventudcalahorra.com\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.consejojuventudcalahorra.com\/&amp;source=gmail&amp;ust=1743491682872000&amp;usg=AOvVaw1RK11eWGi3ccL58OTmgLz0\">www.consejojuventudcalahorra.com<\/a><br \/>\n<a href=\"mailto:coordinacion@consejojuventudcalahorra.com\">coordinacion@consejojuventudcalahorra.com<\/a><br \/>\n@juventudcalahorra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo de la Juventud Comarcal de Calahorra se complace en anunciar una nueva fase dentro de su campa\u00f1a de sensibilizaci\u00f3n social\u00a0\u201cDeja tu huella\u201d, que en esta ocasi\u00f3n pone el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8261,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[96,103,99,24,101],"tags":[],"class_list":["post-8258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asociacionismo","category-cultura","category-formacion-prevencion-igualdad","category-ocio-y-tiempo-libre","category-social"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Deja tu huella&quot; Nueva fase de la campa\u00f1a de sensibilizaci\u00f3n social, ahora centrada en el juego y la educaci\u00f3n en el tiempo libre - Consejo de la Juventud Comarcal de Calahorra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Deja tu huella&quot; Nueva fase de la campa\u00f1a de sensibilizaci\u00f3n social, ahora centrada en el juego y la educaci\u00f3n en el tiempo libre - Consejo de la Juventud Comarcal de Calahorra\" \/>\n<meta property=\"og:description\" content=\"El Consejo de la Juventud Comarcal de Calahorra se complace en anunciar una nueva fase dentro de su campa\u00f1a de sensibilizaci\u00f3n social\u00a0\u201cDeja tu huella\u201d, que en esta ocasi\u00f3n pone el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo de la Juventud Comarcal de Calahorra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/consejojuventudcalahorra\/?locale=es_ES\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-31T07:31:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-25T07:49:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/03\/2025_03_31-Campana-de-Sensibilizacion.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"452\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#\\\/schema\\\/person\\\/d253aff657149d7ba139596a2830074c\"},\"headline\":\"\u00abDeja tu huella\u00bb Nueva fase de la campa\u00f1a de sensibilizaci\u00f3n social, ahora centrada en el juego y la educaci\u00f3n en el tiempo libre\",\"datePublished\":\"2025-03-31T07:31:56+00:00\",\"dateModified\":\"2025-06-25T07:49:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\\\/\"},\"wordCount\":421,\"publisher\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/2025_03_31-Campana-de-Sensibilizacion.jpeg\",\"articleSection\":[\"Asociacionismo\",\"Cultura\",\"Formacion, prevenci\u00f3n e igualdad\",\"ocio y tiempo libre\",\"Social\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\\\/\",\"url\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\\\/\",\"name\":\"\\\"Deja tu huella\\\" Nueva fase de la campa\u00f1a de sensibilizaci\u00f3n social, ahora centrada en el juego y la educaci\u00f3n en el tiempo libre - Consejo de la Juventud Comarcal de Calahorra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/2025_03_31-Campana-de-Sensibilizacion.jpeg\",\"datePublished\":\"2025-03-31T07:31:56+00:00\",\"dateModified\":\"2025-06-25T07:49:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/2025_03_31-Campana-de-Sensibilizacion.jpeg\",\"contentUrl\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/2025_03_31-Campana-de-Sensibilizacion.jpeg\",\"width\":452,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abDeja tu huella\u00bb Nueva fase de la campa\u00f1a de sensibilizaci\u00f3n social, ahora centrada en el juego y la educaci\u00f3n en el tiempo libre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#website\",\"url\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/\",\"name\":\"Consejo de la Juventud Comarcal de Calahorra\",\"description\":\"Ser joven es ser algo m\u00e1s\",\"publisher\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#organization\",\"name\":\"Consejo de la Juventud Comarcal de Calahorra\",\"url\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-CJCC.png\",\"contentUrl\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-CJCC.png\",\"width\":964,\"height\":660,\"caption\":\"Consejo de la Juventud Comarcal de Calahorra\"},\"image\":{\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/consejojuventudcalahorra\\\/?locale=es_ES\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/#\\\/schema\\\/person\\\/d253aff657149d7ba139596a2830074c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f0b7317fa677050c42e96a8889faba4627de455222163352845fae03deb3bb4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f0b7317fa677050c42e96a8889faba4627de455222163352845fae03deb3bb4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f0b7317fa677050c42e96a8889faba4627de455222163352845fae03deb3bb4?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/consejojuventudcalahorra.com\\\/cjcc\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Deja tu huella\" Nueva fase de la campa\u00f1a de sensibilizaci\u00f3n social, ahora centrada en el juego y la educaci\u00f3n en el tiempo libre - Consejo de la Juventud Comarcal de Calahorra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/","og_locale":"es_ES","og_type":"article","og_title":"\"Deja tu huella\" Nueva fase de la campa\u00f1a de sensibilizaci\u00f3n social, ahora centrada en el juego y la educaci\u00f3n en el tiempo libre - Consejo de la Juventud Comarcal de Calahorra","og_description":"El Consejo de la Juventud Comarcal de Calahorra se complace en anunciar una nueva fase dentro de su campa\u00f1a de sensibilizaci\u00f3n social\u00a0\u201cDeja tu huella\u201d, que en esta ocasi\u00f3n pone el [&hellip;]","og_url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/","og_site_name":"Consejo de la Juventud Comarcal de Calahorra","article_publisher":"https:\/\/www.facebook.com\/consejojuventudcalahorra\/?locale=es_ES","article_published_time":"2025-03-31T07:31:56+00:00","article_modified_time":"2025-06-25T07:49:59+00:00","og_image":[{"width":452,"height":640,"url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/03\/2025_03_31-Campana-de-Sensibilizacion.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/#article","isPartOf":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/"},"author":{"name":"admin","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#\/schema\/person\/d253aff657149d7ba139596a2830074c"},"headline":"\u00abDeja tu huella\u00bb Nueva fase de la campa\u00f1a de sensibilizaci\u00f3n social, ahora centrada en el juego y la educaci\u00f3n en el tiempo libre","datePublished":"2025-03-31T07:31:56+00:00","dateModified":"2025-06-25T07:49:59+00:00","mainEntityOfPage":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/"},"wordCount":421,"publisher":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#organization"},"image":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/#primaryimage"},"thumbnailUrl":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/03\/2025_03_31-Campana-de-Sensibilizacion.jpeg","articleSection":["Asociacionismo","Cultura","Formacion, prevenci\u00f3n e igualdad","ocio y tiempo libre","Social"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/","url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/","name":"\"Deja tu huella\" Nueva fase de la campa\u00f1a de sensibilizaci\u00f3n social, ahora centrada en el juego y la educaci\u00f3n en el tiempo libre - Consejo de la Juventud Comarcal de Calahorra","isPartOf":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/#primaryimage"},"image":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/#primaryimage"},"thumbnailUrl":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/03\/2025_03_31-Campana-de-Sensibilizacion.jpeg","datePublished":"2025-03-31T07:31:56+00:00","dateModified":"2025-06-25T07:49:59+00:00","breadcrumb":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/#primaryimage","url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/03\/2025_03_31-Campana-de-Sensibilizacion.jpeg","contentUrl":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/03\/2025_03_31-Campana-de-Sensibilizacion.jpeg","width":452,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/deja-tu-huella-nueva-fase-de-la-campana-de-sensibilizacion-social-ahora-centrada-en-el-juego-y-la-educacion-en-el-tiempo-libre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/consejojuventudcalahorra.com\/cjcc\/"},{"@type":"ListItem","position":2,"name":"\u00abDeja tu huella\u00bb Nueva fase de la campa\u00f1a de sensibilizaci\u00f3n social, ahora centrada en el juego y la educaci\u00f3n en el tiempo libre"}]},{"@type":"WebSite","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#website","url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/","name":"Consejo de la Juventud Comarcal de Calahorra","description":"Ser joven es ser algo m\u00e1s","publisher":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/consejojuventudcalahorra.com\/cjcc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#organization","name":"Consejo de la Juventud Comarcal de Calahorra","url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#\/schema\/logo\/image\/","url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/09\/Logo-CJCC.png","contentUrl":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-content\/uploads\/2025\/09\/Logo-CJCC.png","width":964,"height":660,"caption":"Consejo de la Juventud Comarcal de Calahorra"},"image":{"@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/consejojuventudcalahorra\/?locale=es_ES"]},{"@type":"Person","@id":"https:\/\/consejojuventudcalahorra.com\/cjcc\/#\/schema\/person\/d253aff657149d7ba139596a2830074c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7f0b7317fa677050c42e96a8889faba4627de455222163352845fae03deb3bb4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f0b7317fa677050c42e96a8889faba4627de455222163352845fae03deb3bb4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f0b7317fa677050c42e96a8889faba4627de455222163352845fae03deb3bb4?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/consejojuventudcalahorra.com\/cjcc\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/posts\/8258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/comments?post=8258"}],"version-history":[{"count":3,"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/posts\/8258\/revisions"}],"predecessor-version":[{"id":8988,"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/posts\/8258\/revisions\/8988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/media\/8261"}],"wp:attachment":[{"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/media?parent=8258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/categories?post=8258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consejojuventudcalahorra.com\/cjcc\/wp-json\/wp\/v2\/tags?post=8258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}